{"id":3876,"date":"2016-11-29T15:27:25","date_gmt":"2016-11-29T05:27:25","guid":{"rendered":"https:\/\/thirstyaff.wpengine.com\/?p=3876"},"modified":"2017-12-21T15:26:58","modified_gmt":"2017-12-21T05:26:58","slug":"5-people-beat-odds-using-blogging","status":"publish","type":"post","link":"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging","title":{"rendered":"5 personas que vencieron a los pron\u00f3sticos gracias a sus blogs"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04c9e57cc38\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #38ad9c;color:#38ad9c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #38ad9c;color:#38ad9c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04c9e57cc38\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging\/#1_Rand_Fishkin\" >#1 Rand Fishkin<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging\/#2_Gary_Vaynerchuk\" >#2 Gary Vaynerchuk<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging\/#3_Pat_Flynn\" >#3 Pat Flynn<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging\/#4_Matthew_Woodward\" >#4 Matthew Woodward<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging\/#5_Brian_Clark\" >#5 Brian Clark<\/a><\/li><\/ul><\/nav><\/div>\n<p>As\u00ed que quieres ser bloguero, \u00bfeh? No puedo culparte y, con las incre\u00edbles historias que has o\u00eddo sobre este trabajo, \u00a1seguro que est\u00e1s deseando que llegue tu turno!<\/p>\n<p>Cuando preguntas \"\u00bfA qu\u00e9 te dedicas?\" y alguien dice que trabaja como \"Blogger\", \u00a1se levantan muchas cejas! \u00bfQu\u00e9 significa eso? \u00bfEs realmente un trabajo? \u00bfRealmente te pagan por ello? Aunque ser bloguero no suene como un trabajo de verdad, cr\u00e9eme, hay mucha gente ah\u00ed fuera que ha tenido \u00e9xito en esto.<\/p>\n<p>El blogging es tambi\u00e9n una de las maneras m\u00e1s f\u00e1ciles de vender; que es tambi\u00e9n la raz\u00f3n por la cual la gente que abraz\u00f3 este trabajo lleg\u00f3 a ser acertada en \u00e9l.<\/p>\n<p>Muchas personas en el campo del marketing de afiliaci\u00f3n son tambi\u00e9n blogueros, as\u00ed que para inspirarte hemos reunido los perfiles de 5 blogueros incre\u00edbles que son empresarios a los que admiramos:<\/p>\n<h2><span class=\"ez-toc-section\" id=\"1_Rand_Fishkin\"><\/span>#1 Rand Fishkin<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/rand.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3890 size-full\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/rand.jpg\" alt=\"rand fishkin blogging\" width=\"960\" height=\"540\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/rand.jpg 960w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/rand-300x169.jpg 300w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/rand-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>Probablemente hayas o\u00eddo hablar de Rand Fishkin aunque no te dediques al marketing de afiliaci\u00f3n. Esto se debe a que es uno de los pioneros en SEO y, aunque es uno de los nombres m\u00e1s destacados en el mercado de afiliaci\u00f3n, comenz\u00f3 como un desertor universitario que empez\u00f3 a escribir sobre optimizaci\u00f3n de motores de b\u00fasqueda en 2004. Naci\u00f3 en Flemington, Nueva Jersey, pero creci\u00f3 en Seattle, Washington. En 2000, Fishkin abandon\u00f3 la Universidad de Washington cuando decidi\u00f3 trabajar para la peque\u00f1a empresa de su madre que se dedicaba al dise\u00f1o y marketing web. En 2004 cre\u00f3 el blog SEOmoz, que con el tiempo se convirti\u00f3 en una de las comunidades m\u00e1s destacadas en t\u00e9rminos de marketing.<\/p>\n<p>En 2007, Fishkin se convirti\u00f3 en Consejero Delegado de SEOmoz, Inc. <a href=\"https:\/\/moz.com\/\">Moz<\/a>). La empresa de software que cre\u00f3 entonces con su madre es ahora uno de los mayores nombres de Internet. Ese mismo a\u00f1o le propuso matrimonio y se cas\u00f3 con su novia de toda la vida, Geraldine DeRuiter, en 2008. Seis a\u00f1os m\u00e1s tarde, Rand fue capaz de ampliar su empresa que comenz\u00f3 con 7 empleados a 134 y contando. En 2013, SEOmoz cambi\u00f3 de marca y pas\u00f3 a llamarse Moz, que se centr\u00f3 en el software de marketing. Al a\u00f1o siguiente, Rand promovi\u00f3 a Sarah Bird, directora de operaciones, para que ocupara su lugar mientras \u00e9l lidiaba con algunos problemas personales. Se convirti\u00f3 en un colaborador individual de la empresa mientras manten\u00eda su t\u00edtulo de Mago de Moz y Presidente del Consejo de Administraci\u00f3n. Adem\u00e1s de Moz, Fishkin tambi\u00e9n es el cofundador de Inbound.org, un sitio que se dedica a compartir art\u00edculos de marketing en toda la web con Dharmesh Shah, pero el sitio fue vendido en 2014 a Hubspot. Rand se hizo conocido por su serie Whiteboard Friday y a menudo es invitado como orador principal en numerosos seminarios y conferencias de marketing. Anteriormente colabor\u00f3 en dos libros: Art of SEO e Inbound Marketing &amp; SEO. Tambi\u00e9n particip\u00f3 en el consejo de administraci\u00f3n de Minted. \u00c9l y su esposa tambi\u00e9n invirtieron en Techstars Seattle en 2015.<\/p>\n<p>Tambi\u00e9n puede leer sobre \u00e9l en el Seatte Times, donde ha sido rese\u00f1ado. Tambi\u00e9n apareci\u00f3 en Puget Sound Business Journal's 40 Under 40, BusinessWeek's 30 Under 30, as\u00ed como en otras publicaciones. Sin embargo, entre las publicaciones en las que ha aparecido, est\u00e1 muy orgulloso de su distinci\u00f3n en el blog Everywhereist. Cuando no est\u00e1 trabajando, a Fishkin le gusta viajar, el f\u00fatbol de la NFL, la cerveza, el whisky, la comida, la ciencia, navegar por Internet y, por supuesto, Adventure Time.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"2_Gary_Vaynerchuk\"><\/span>#2 Gary Vaynerchuk<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/gary.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-3891 size-full\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/gary.jpg\" alt=\"gary vaynerchuck blogging\" width=\"750\" height=\"422\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/gary.jpg 750w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/gary-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Gary es un conocido orador p\u00fablico en eventos como SXSW y Le Web, que puede verse en su canal de YouTube. Tambi\u00e9n ha aparecido en la lista Crain's 40 Under 40 y en Fortune en los \u00faltimos dos a\u00f1os. Adem\u00e1s, Gary ha aparecido en el New York Times y otras revistas de negocios. Este empresario de \u00e9xito naci\u00f3 en Babrusk (Bielorrusia), en la antigua Uni\u00f3n de Rep\u00fablicas Socialistas Sovi\u00e9ticas. Sus padres fueron de los afortunados que llegaron a Estados Unidos a trav\u00e9s de un programa de intercambio en el que los jud\u00edos sovi\u00e9ticos ten\u00edan la oportunidad de emigrar a Am\u00e9rica a cambio de ayuda alimentaria. Finalmente aterrizaron en Nueva York y su familia comparti\u00f3 un peque\u00f1o apartamento en Queens, Nueva York. Su padre trabajaba en una licorer\u00eda propiedad de uno de sus parientes en Nueva Jersey. Con el tiempo, tambi\u00e9n se trasladaron y se establecieron en Nueva Jersey.<\/p>\n<p>Las habilidades empresariales de Vaynerchuk comenzaron a una edad temprana, cuando empez\u00f3 a arrancar flores de los patios de sus vecinos. Dotado de encantos naturales, empez\u00f3 a venderlas y, con el tiempo, subi\u00f3 de nivel hasta vender limonadas por su barrio. Consigui\u00f3 venderlas en distintos lugares, donde recog\u00eda sus beneficios montado en una gran rueda. Al llegar a la adolescencia, empez\u00f3 a vender cromos de b\u00e9isbol, donde desarroll\u00f3 sus picarescas t\u00e1cticas de venta. All\u00ed lleg\u00f3 a ganar unos mil a la semana. Sin embargo, su padre le coloc\u00f3 en el negocio familiar a la edad de 14 a\u00f1os, lo que le hizo infeliz al principio.<\/p>\n<p>Tras licenciarse en la universidad, se hizo cargo del negocio familiar de vinos y lo convirti\u00f3 en un negocio millonario en s\u00f3lo 5 a\u00f1os. De una tienda de vinos de $3 millones, fue capaz de convertirla en un negocio de $60 millones. Hoy en d\u00eda es el destacado propietario de VaynerMedia, conocida tambi\u00e9n como una de las mejores agencias en l\u00ednea. Adem\u00e1s de su propia empresa, tambi\u00e9n es inversor y capitalista de riesgo en varias empresas como Facebook, Uber, Tumblr, Twitter y muchas m\u00e1s antes de cofundar VaynerRSE. Gary tambi\u00e9n es <a class=\"thirstylink\" rel=\"nofollow noindex\" target=\"_blank\" title=\"Hostpapa\" href=\"https:\/\/thirstyaffiliates.com\/es\/recommends\/hostpapa\" data-shortcode=\"true\">alojamiento<\/a> el #AskGaryVee Show que aborda temas relacionados con la creaci\u00f3n de empresas, medios de comunicaci\u00f3n social, as\u00ed como las empresas familiares mientras que da consejos a su audiencia. Todos sus programas est\u00e1n disponibles en Stitcher, SoundCloud e iTunes si est\u00e1s interesado en escucharle hablar y tambi\u00e9n puedes visitar su p\u00e1gina web para m\u00e1s informaci\u00f3n en <a href=\"http:\/\/www.garyvaynerchuk.com\/\">GaryVaynerChuk.com<\/a>.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"3_Pat_Flynn\"><\/span>#3 Pat Flynn<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-3895 size-large\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1-1024x512.jpg\" alt=\"pat flynn blogging\" width=\"640\" height=\"320\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1-1024x512.jpg 1024w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1-300x150.jpg 300w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1-768x384.jpg 768w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1-1536x768.jpg 1536w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/pat_flynn_1.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Aclamado como uno de los blogueros m\u00e1s influyentes del mercado digital, Patrick Flynn empez\u00f3 a trabajar en este negocio despu\u00e9s de perder su empleo hace unos a\u00f1os. Trabaj\u00f3 en su <a href=\"http:\/\/www.smartpassiveincome.com\/\">Ingresos pasivos inteligentes<\/a> en 2008 con el objetivo de compartir estrategias sobre c\u00f3mo hizo crecer su negocio online. Seg\u00fan Flynn, empez\u00f3 a escribir sus reflexiones sobre la preparaci\u00f3n de un examen LEED, tambi\u00e9n conocido como examen de arquitectura. Luego convirti\u00f3 sus notas en un libro electr\u00f3nico despu\u00e9s de que ganara tr\u00e1fico y vendiera alrededor de $8.000 en su primer mes. Fue tambi\u00e9n ese mismo a\u00f1o cuando lanz\u00f3 por primera vez GreenExpertAcademy.com, donde escrib\u00eda sobre productos. Despu\u00e9s de sus exitosas ventas de libros electr\u00f3nicos, Flynn abri\u00f3 oficialmente su blog Smart Passive Income o tambi\u00e9n conocido como SmartPassiveIncome.com. El sitio le ayuda a rastrear diferentes sitios web mientras se mantiene al d\u00eda con sus otros proyectos. Recibi\u00f3 su primer ingreso de 6 d\u00edgitos un a\u00f1o despu\u00e9s.<\/p>\n<p><strong>\u00a0<\/strong>Actualmente dirige un programa de podcast regular para toda su audiencia y lectores. En los \u00faltimos meses, los ingresos de Pat se estiman en unos $120.000 d\u00f3lares mensuales, gracias a su dedicaci\u00f3n y duro trabajo. En su tiempo libre, Pat disfruta con su mujer, April, y sus hijos Keoni y Kailani. Tambi\u00e9n adora a su perro Gizmo. Tambi\u00e9n le gusta la m\u00fasica, leer libros, jugar al baloncesto y StarWars Battlefront.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"4_Matthew_Woodward\"><\/span>#4 Matthew Woodward<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/matt.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3893\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/matt-1024x548.jpg\" alt=\"matthew woodward blogging\" width=\"750\" height=\"402\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/matt-1024x548.jpg 1024w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/matt-300x161.jpg 300w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/matt-768x411.jpg 768w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/matt.jpg 1479w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Matt tiene 28 a\u00f1os <a href=\"http:\/\/www.matthewwoodward.co.uk\/\">blogger de marketing<\/a> que ha obtenido numerosos premios por su trabajo. La carrera de Woodward comenz\u00f3 a los 13 a\u00f1os, cuando escrib\u00eda cr\u00edticas de videojuegos para NintendoPhiles. Con el tiempo, su inter\u00e9s por la escritura le llev\u00f3 a crear su primera comunidad web de juegos competitivos, que permit\u00eda a otros jugadores compartir breves clips y demos en los que mostraban sus mejores acciones. En 2003 se convirti\u00f3 en la primera persona en hacer un 360 no scope en un juego FPS que, cuando public\u00f3 su v\u00eddeo, acab\u00f3 ganando muchos fans.<\/p>\n<p>A\u00f1os m\u00e1s tarde se convirti\u00f3 en el responsable de marketing online en Europa de algunos de los mayores distribuidores de productos online del pa\u00eds. Entre sus clientes se encontraban Asda, Samsung, Tesco e incluso Motorola. Aunque tuvo \u00e9xito haciendo campa\u00f1as para estas empresas, le pareci\u00f3 que era lento y se estaba quedando atr\u00e1s respecto al ritmo siempre cambiante de la web. Decidi\u00f3 cambiar de rumbo hace tres a\u00f1os, cuando empez\u00f3 a trabajar para s\u00ed mismo. Esto le permiti\u00f3 ampliar y desarrollar sus conocimientos. Lleg\u00f3 a crear 40 sitios web. M\u00e1s tarde se interes\u00f3 por el SEO. Con pruebas y experimentos constantes, Woodward se convirti\u00f3 en uno de los expertos del tr\u00e1fico web.<\/p>\n<p>Hoy en d\u00eda es uno de los nombres de confianza en SEO y marketing de afiliaci\u00f3n. Su blog habla de sus experiencias como un vendedor del afiliado y proporciona a las personas con excelentes tutoriales, as\u00ed como asesoramiento a aquellos que est\u00e1n en necesidad de su experiencia. Sus ingresos se estiman en alrededor de $800,000 a partir de octubre de 2016.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"5_Brian_Clark\"><\/span>#5 Brian Clark<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/brian.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3894 size-full\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/brian.jpg\" alt=\"brian clark blogging\" width=\"613\" height=\"660\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/brian.jpg 613w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2016\/11\/brian-279x300.jpg 279w\" sizes=\"(max-width: 613px) 100vw, 613px\" \/><\/a><\/p>\n<p>Si ha o\u00eddo hablar de <a href=\"http:\/\/www.copyblogger.com\/\">Copyblogger<\/a> entonces es probable que hayas o\u00eddo hablar del nombre de Brian Clark. Su trabajo comenz\u00f3 ya en 1998 y, en 1999, Clark logr\u00f3 su primer \u00e9xito en los negocios en l\u00ednea, todo gracias al marketing de contenidos. M\u00e1s tarde lanz\u00f3 otros dos negocios en l\u00ednea con la ayuda del marketing y las herramientas en l\u00ednea.<\/p>\n<p>En 2006, Clark fund\u00f3 Copyblogger, que comenz\u00f3 como un blog en 2006. Su sitio tiene como objetivo ayudar a personas como \u00e9l a convertirse en redactores excepcionales y expertos en contenidos en general. Tras su \u00e9xito, lanz\u00f3 Copyblogger Media, que ayud\u00f3 a impulsar varias empresas derivadas. Entre ellas, Synthesis, Scribe, Premise y StudioPress.<\/p>\n<p>Hoy en d\u00eda, Brian sigue participando activamente en la gesti\u00f3n de la Copyblogger y contribuye a sus otros proyectos que incluyen dar estrategias y consejos a los consultores, entrenadores, aut\u00f3nomos y personas que est\u00e1n interesadas en general en su l\u00ednea de trabajo. Tambi\u00e9n se ha informado de que Clark hizo 8 cifras en sus ingresos anuales sin siquiera publicidad por lo que es uno de los mejores estimulantes de la industria de marketing de contenidos.<\/p>\n<hr \/>\n<p>As\u00ed que ah\u00ed lo tienes, \u00a1cinco de los nombres l\u00edderes en el mundo de los negocios online que puedes seguir! Si est\u00e1s interesado en ser uno de estos l\u00edderes de \u00e9xito, la clave es empezar ahora. No es demasiado tarde para ti, s\u00f3lo hace falta mucha paciencia y ganas de aprender.<\/p>","protected":false},"excerpt":{"rendered":"<p>As\u00ed que quieres ser bloguero, \u00bfeh? No puedo culparte y con las incre\u00edbles historias que has o\u00eddo sobre este trabajo, \u00a1probablemente no puedas esperar a que llegue tu turno! Cuando preguntas \"\u00bfA qu\u00e9 te dedicas?\" y alguien te dice que trabaja como \"Blogger\", un<\/p>\n<p><a class=\"read-more\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/5-people-beat-odds-using-blogging\">Seguir leyendo<\/a><\/p>","protected":false},"author":1576,"featured_media":590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[249],"tags":[],"class_list":["post-3876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies-and-interviews"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/3876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/users\/1576"}],"replies":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/comments?post=3876"}],"version-history":[{"count":0,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/3876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/media\/590"}],"wp:attachment":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/media?parent=3876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/categories?post=3876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/tags?post=3876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}