{"id":6664,"date":"2017-10-31T08:00:58","date_gmt":"2017-10-30T22:00:58","guid":{"rendered":"https:\/\/thirstyaff.wpengine.com\/?p=6664"},"modified":"2019-11-19T08:00:11","modified_gmt":"2019-11-18T22:00:11","slug":"interview-affiliate-jansie-blom","status":"publish","type":"post","link":"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom","title":{"rendered":"Entrevista con un afiliado: Jansie Blom"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04ca304cfdc\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #38ad9c;color:#38ad9c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #38ad9c;color:#38ad9c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04ca304cfdc\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\/#Q_What_is_your_site_about_Introduce_yourself_and_how_you_got_into_doing_what_youre_currently_doing%E2%80%A6\" >P \u00bfDe qu\u00e9 trata tu p\u00e1gina web? Pres\u00e9ntese y explique c\u00f3mo lleg\u00f3 a hacer lo que hace actualmente...<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\/#Q_How_do_you_use_affiliate_marketing_on_your_site\" >P \u00bfC\u00f3mo utiliza el marketing de afiliaci\u00f3n en su sitio web?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\/#Q_You_have_a_unique_writing_style_its_quite_personable_and_funny_like_youre_talking_to_a_mate_do_you_find_this_helps_improve_the_effectiveness_of_your_reviews_or_makes_them_easier_to_write\" >P Tiene un estilo de escritura \u00fanico, muy personal y divertido, como si hablara con un amigo. \u00bfCree que esto ayuda a mejorar la eficacia de sus cr\u00edticas o facilita su redacci\u00f3n?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\/#Q_So_Jansie_from_the_bottom_of_your_heart_with_no_holds_barred_what_do_you_think_of_SEO_and_keyword_density\" >P Entonces, Jansie, de todo coraz\u00f3n, sin tapujos, \u00bfqu\u00e9 opinas del SEO y de la densidad de palabras clave?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\/#Q_What_would_you_say_is_the_most_important_element_of_your_strategy_that_others_can_learn_from\" >P \u00bfCu\u00e1l dir\u00eda que es el elemento m\u00e1s importante de su estrategia del que otros pueden aprender?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\/#Q_Where_can_people_find_you_and_follow_what_youre_doing\" >P \u00bfD\u00f3nde puede la gente encontrarle y seguir lo que hace?<\/a><\/li><\/ul><\/nav><\/div>\n<p><a href=\"https:\/\/thirstyaffiliates.com\/es\/?attachment_id=6668\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-6668 size-full\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/10\/jansie-blom-interview.jpg\" alt=\"Jansie Blom Entrevista a profesionales del marketing de afiliaci\u00f3n\" width=\"850\" height=\"300\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/10\/jansie-blom-interview.jpg 850w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/10\/jansie-blom-interview-300x106.jpg 300w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/10\/jansie-blom-interview-768x271.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a><\/p>\n<p>\u00a1Bienvenidos a otra entrevista con un afiliado!<\/p>\n<p>De vez en cuando publicamos nuestras charlas con los vendedores afiliados que nos llaman la atenci\u00f3n haciendo algo \u00fanico o digno de menci\u00f3n de lo que otros podr\u00edan aprender. El invitado de hoy es Jansie Blom y sin duda encaja en esa descripci\u00f3n.<\/p>\n<p>Dirige un sitio web llamado <a href=\"http:\/\/raspandrivet.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Escofina y remache<\/a> que se centra en rese\u00f1as personales de equipos para actividades al aire libre, herramientas e incluso campa\u00f1as de crowdfunding. Su sitio es brutalmente honesto y eso es lo que me llam\u00f3 la atenci\u00f3n porque la mayor\u00eda de los afiliados tienden a endulzar sus opiniones con el fin de ganar un d\u00f3lar por referirlos en adelante. Jansie no, \u00e9l se lo cuenta todo sin tapujos.<\/p>\n<p>Le tend\u00ed la mano <a href=\"https:\/\/wordpress.org\/support\/topic\/good-plugin-2341\/\" target=\"_blank\" rel=\"noopener noreferrer\">despu\u00e9s de revisar<\/a> ThirstyAffiliates (justo antes de nuestro relanzamiento 3.0, pero aun as\u00ed nos dio un gran 4\/5, lo que es todo un logro viniendo de \u00e9l).<\/p>\n<p>Sin m\u00e1s pre\u00e1mbulos, \u00a1dejar\u00e9 que Jansie tome el micr\u00f3fono!<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Q_What_is_your_site_about_Introduce_yourself_and_how_you_got_into_doing_what_youre_currently_doing%E2%80%A6\"><\/span>P: \u00bfDe qu\u00e9 trata su p\u00e1gina web? Pres\u00e9ntese y explique c\u00f3mo empez\u00f3 a hacer lo que hace actualmente...<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Hola Blair,<\/p>\n<p>Gracias por la oportunidad. Se lo agradezco mucho. (Me encantan los australianos, a pesar de que somos enemigos mortales en el campo de rugby).<\/p>\n<p>Me llamo Jansie. La \u201cJ\u201d se pronuncia como una \u201cY\u201d, y mi nombre rima con mar joven.<\/p>\n<p>Soy redactor publicitario y comercializador de contenidos (esto \u00faltimo parece que ya es algo).<\/p>\n<p>Empec\u00e9 a escribir hace unos a\u00f1os, despu\u00e9s de haber hecho de todo, incluida la calificaci\u00f3n como fabricante de herramientas y haciendo un per\u00edodo como vendedor para una empresa de fabricaci\u00f3n de carburo.<\/p>\n<p>Siempre he tenido facilidad para hilar frases, pero tard\u00e9 a\u00f1os en adentrarme m\u00e1s all\u00e1 del cuello.<\/p>\n<p>Mi sitio es una fuente fiable de rese\u00f1as de productos. Compro productos, los pruebo y los desvelo en extensos art\u00edculos. Analizo cualquier producto que nos facilite la vida, ya sea de interior o de exterior. Y aunque prefiero escribir sobre art\u00edculos de exterior no electr\u00f3nicos, estoy abierto a rese\u00f1ar cualquier art\u00edculo sensato.<\/p>\n<p>Yo tambi\u00e9n sol\u00eda respaldar campa\u00f1as de crowdfunding, pero el panorama del crowdfunding est\u00e1 lleno de minas terrestres, as\u00ed que decid\u00ed dejar de hacerlo. De hecho, intento denunciar las malas campa\u00f1as de crowdfunding. Lo considero un deber.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Q_How_do_you_use_affiliate_marketing_on_your_site\"><\/span>P: \u00bfC\u00f3mo utiliza el marketing de afiliaci\u00f3n en su sitio web?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La mayor\u00eda de mis rese\u00f1as contienen enlaces afiliados de alg\u00fan tipo. Si el producto no me gusta, no pongo enlaces de afiliado. He tenido uno de esos. Creo que es justo que mis lectores sepan cu\u00e1ndo un producto es deficiente y por qu\u00e9 lo es.<\/p>\n<p>Pero...<\/p>\n<p>Mi objetivo es tener un sitio web con contenido de calidad que incluya productos disponibles a trav\u00e9s de enlaces de afiliados. Si puedo monetizar de esa manera, elimino la necesidad de monetizar con anuncios.<\/p>\n<p>En cuanto a c\u00f3mo gestiono mis enlaces de afiliado, ThirstyAffiliates desempe\u00f1a un papel ENORME.<\/p>\n<p>Yo sol\u00eda manejar los enlaces de afiliados manualmente. Visitaba Amazon, obten\u00eda el enlace de SiteStripe y lo introduc\u00eda en mi contenido.<\/p>\n<p>Pero un d\u00eda me acord\u00e9 de haber le\u00eddo sobre la ocultaci\u00f3n de enlaces de afiliados unos a\u00f1os antes.<\/p>\n<p>As\u00ed que busqu\u00e9 el t\u00e9rmino en Google y me encontr\u00e9 con numerosos posts sobre herramientas de gesti\u00f3n de afiliados.<\/p>\n<p>Eleg\u00ed ThirstyAffiliates, y me alegro de haberlo hecho.<\/p>\n<p>Como tantas cosas en la vida, oyes hablar de algo que podr\u00eda beneficiarte, piensas \"s\u00ed, claro\" y te olvidas de ello.<\/p>\n<p>Luego empiezas a utilizarlo y te dan ganas de darte una patada en la cabeza por haber sido tan obtuso.<\/p>\n<p>As\u00ed es la vida para m\u00ed, en cualquier caso. Y eso es lo que siento por ThirstyAffiliates. Es una herramienta incre\u00edble. Deber\u00eda haber empezado a utilizarla al principio de mi andadura.<\/p>\n<p>Por ejemplo, pongo mucho empe\u00f1o en dirigir a mis lectores al mejor Amazon para su ubicaci\u00f3n (donde yo uso Amazon). TA me permite a\u00f1adir la geolocalizaci\u00f3n.<\/p>\n<p>Tambi\u00e9n est\u00e1 la gesti\u00f3n centralizada de los enlaces de afiliaci\u00f3n. Muy pr\u00e1ctico.<\/p>\n<p>Una de mis funciones favoritas es el enlace autom\u00e1tico. Es una funci\u00f3n INCRE\u00cdBLE. Tengo que controlarme para no excederme. Si pudiera, convertir\u00eda todo en un enlace de afiliado.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Q_You_have_a_unique_writing_style_its_quite_personable_and_funny_like_youre_talking_to_a_mate_do_you_find_this_helps_improve_the_effectiveness_of_your_reviews_or_makes_them_easier_to_write\"><\/span>P: Tiene un estilo de escritura \u00fanico, bastante personal y divertido, como si hablara con un amigo. \u00bfCree que esto ayuda a mejorar la eficacia de sus cr\u00edticas o facilita su redacci\u00f3n?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Muchas gracias. Muy amable por decir eso.<\/p>\n<p>La capacidad de atenci\u00f3n es un problema. Eso se oye todo el tiempo. Pero eso no significa que el contenido deba ser breve en nombre de lo que dicen los \u201cgur\u00fas\u201d.<\/p>\n<p>Significa que tienes que ser inteligente a la hora de comunicarte.<\/p>\n<p>La clave es que la informaci\u00f3n sea larga y la redacci\u00f3n breve. \u00bfTiene sentido?<\/p>\n<p>Intentar\u00e9 explicarlo...<\/p>\n<p>Aunque mis art\u00edculos tienen miles de palabras, los creo de tal manera que te enga\u00f1an haci\u00e9ndote creer que son peque\u00f1os trozos comestibles.<\/p>\n<p>Y s\u00ed, estoy hablando con un amigo. Quiero mostrarte lo incre\u00edble que es este producto, sin adverbios ni signos de exclamaci\u00f3n. Y sin usar t\u00edtulos de \"clickbait\" para atraerte. Los amigos no hablan a sus amigos como si fueran clientes.<\/p>\n<p>\u00bfFunciona?<\/p>\n<p>No es para todos.<\/p>\n<p>Pero, de nuevo, no intento complacer a todo el mundo.<\/p>\n<p>Despu\u00e9s de ver grabaciones de pantalla de personas que utilizan mi sitio, me complace decir que funciona bastante bien.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Q_So_Jansie_from_the_bottom_of_your_heart_with_no_holds_barred_what_do_you_think_of_SEO_and_keyword_density\"><\/span>P: Entonces, Jansie, de todo coraz\u00f3n, sin tapujos, \u00bfqu\u00e9 opinas del SEO y de la densidad de palabras clave?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ugh.<\/p>\n<p>Estoy harto de o\u00edr hablar de SEO.<\/p>\n<p>Si tiene que elegir entre SEO (signifique lo que signifique para usted) y contenido, elija contenido.<\/p>\n<p>\u00bfDensidad de palabras clave?<\/p>\n<p>Escriba art\u00edculos largos. Eso te dar\u00e1 densidad de palabras clave.<\/p>\n<p>Dedique m\u00e1s tiempo a crear contenidos y menos a preocuparse por el SEO.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Q_What_would_you_say_is_the_most_important_element_of_your_strategy_that_others_can_learn_from\"><\/span>P: \u00bfCu\u00e1l dir\u00eda que es el elemento m\u00e1s importante de su estrategia del que otros pueden aprender?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Deja Netflix, c\u00e9ntrate en una cosa, piensa a largo plazo y no te rindas. Y crea una lista de distribuci\u00f3n. (Es dif\u00edcil, mucho m\u00e1s que mejorar el SEO).<\/p>\n<p>Olv\u00eddese del \u00e9xito de la noche a la ma\u00f1ana. No le ocurre a todo el mundo.<\/p>\n<p>No puedo darte un solo elemento.<\/p>\n<p>Puedo decir: La gracia de Dios + concentraci\u00f3n + determinaci\u00f3n + tenacidad + calidad = \u00e9xito.<\/p>\n<p>Me encanta un dicho que se atribuye a Conor McGregor: \u201cAqu\u00ed no hay talento, esto es trabajo duro...\u201d.\u201d<\/p>\n<p>Excelente.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Q_Where_can_people_find_you_and_follow_what_youre_doing\"><\/span>P: \u00bfD\u00f3nde puede encontrarle la gente y seguir lo que hace?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Pueden visitar mi sitio web, <a href=\"http:\/\/raspandrivet.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">RaspAndRivet.com<\/a>. (<a href=\"http:\/\/raspandrivet.com\/newsletter\/\" target=\"_blank\" rel=\"noopener noreferrer\">Suscr\u00edbase al bolet\u00edn<\/a>)<\/p>\n<p>Tengo una p\u00e1gina en Facebook, pero hace poco he creado un grupo al que me gustar\u00eda que la gente se uniera: <a href=\"https:\/\/www.facebook.com\/groups\/662947687228346\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/groups\/662947687228346\/<\/a><\/p>\n<p>En Twitter, encu\u00e9ntrame en <a href=\"https:\/\/twitter.com\/jansieblom\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/twitter.com\/jansieblom<\/a><\/p>\n<p>Gracias de nuevo, Blair, y todo lo mejor para tu negocio (\u00a1y para tu equipo de rugby!).<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Bienvenidos a otra entrevista con un afiliado! De vez en cuando publicamos nuestras charlas con los vendedores afiliados que nos llaman la atenci\u00f3n haciendo algo \u00fanico o digno de menci\u00f3n que otros podr\u00edan aprender. El invitado de hoy es Jansie Blom y definitivamente se ajusta a esa descripci\u00f3n. Dirige un sitio llamado Rasp<\/p>\n<p><a class=\"read-more\" href=\"https:\/\/thirstyaffiliates.com\/es\/blog\/interview-affiliate-jansie-blom\">Seguir leyendo<\/a><\/p>","protected":false},"author":1,"featured_media":6668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[249],"tags":[],"class_list":["post-6664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies-and-interviews"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/6664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/comments?post=6664"}],"version-history":[{"count":0,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/6664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/media\/6668"}],"wp:attachment":[{"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/media?parent=6664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/categories?post=6664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/es\/wp-json\/wp\/v2\/tags?post=6664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}