{"id":1177,"date":"2013-01-30T09:00:45","date_gmt":"2013-01-29T23:00:45","guid":{"rendered":"https:\/\/thirstyaff.wpengine.com\/?p=1177"},"modified":"2024-06-12T08:26:06","modified_gmt":"2024-06-12T12:26:06","slug":"affiliate-marketing-banners-text-links","status":"publish","type":"post","link":"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-marketing-banners-text-links\/","title":{"rendered":"Quelle est la meilleure solution pour le marketing d'affiliation : Banni\u00e8res ou liens textuels"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenu<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57c961406f3\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #38ad9c;color:#38ad9c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #38ad9c;color:#38ad9c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57c961406f3\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-marketing-banners-text-links\/#Using_Banners_In_Affiliate_Marketing\" >Utilisation des banni\u00e8res dans le marketing d'affiliation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-marketing-banners-text-links\/#Using_Text_Links_In_Affiliate_Marketing\" >Utilisation des liens textuels dans le marketing d'affiliation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-marketing-banners-text-links\/#So_which_is_best_to_use_for_affiliate_marketing\" >Quelle est donc la meilleure solution pour le marketing d'affiliation ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-marketing-banners-text-links\/#Test_And_Tune_Your_Strategy\" >Testez et ajustez votre strat\u00e9gie<\/a><\/li><\/ul><\/nav><\/div>\n<p><img decoding=\"async\" class=\"alignright wp-image-1180 size-medium\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2013\/01\/Standard_web_banner_ad_sizes.svg_-300x281.png\" alt=\"Banni\u00e8res et liens textuels dans le marketing d&#039;affiliation\" width=\"300\" height=\"281\" \/>Il s'agit d'une question tr\u00e8s difficile, qui pose probl\u00e8me \u00e0 de nombreux sp\u00e9cialistes du marketing d'affiliation : faut-il utiliser des banni\u00e8res pour le marketing d'affiliation ou des liens textuels ?<\/p>\n<p>La r\u00e9ponse est que cela d\u00e9pend.<\/p>\n<p>Les deux m\u00e9thodes de promotion des offres d'affiliation peuvent g\u00e9n\u00e9rer des ventes et ont chacune leurs avantages.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Using_Banners_In_Affiliate_Marketing\"><\/span>Utilisation des banni\u00e8res dans le marketing d'affiliation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Examinons tout d'abord les banni\u00e8res.<\/p>\n<p>Les banni\u00e8res sont g\u00e9n\u00e9ralement de petits carr\u00e9s de 125\u00d7125 pixels, de grands carr\u00e9s de 250\u00d7250 pixels ou des tableaux de classement de 468\u00d760 pixels.<\/p>\n<p>L'avantage des banni\u00e8res est qu'elles peuvent attirer l'attention gr\u00e2ce \u00e0 des graphiques et des animations bien con\u00e7us qui incitent l'utilisateur \u00e0 regarder la banni\u00e8re.<\/p>\n<p>Si vous utilisez une banni\u00e8re anim\u00e9e, il est pr\u00e9f\u00e9rable d'opter pour celles qui ne comportent que deux diapositives avec un appel \u00e0 l'action fort sur la derni\u00e8re diapositive.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Using_Text_Links_In_Affiliate_Marketing\"><\/span>Utilisation des liens textuels dans le marketing d'affiliation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les liens de texte, quant \u00e0 eux, peuvent \u00eatre utiles pour <a title=\"Comment ajouter automatiquement des liens d&#039;affiliation contextuels \u00e0 vos articles de blog\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/add-contextual-affiliate-links-blog-posts-automatically\/\">marketing d'affiliation contextuel<\/a>\u00a0et offrent aux affili\u00e9s la possibilit\u00e9 d'int\u00e9grer leurs liens d'affiliation dans le contenu de la page web.<\/p>\n<p>En tant qu'affili\u00e9, cela vous permet de g\u00e9n\u00e9rer un appel \u00e0 l'action tr\u00e8s cibl\u00e9, dont il a \u00e9t\u00e9 d\u00e9montr\u00e9 qu'il convertit mieux que les banni\u00e8res classiques.<\/p>\n<p>Contrairement aux banni\u00e8res, les liens de texte ne souffrent g\u00e9n\u00e9ralement pas \u201c<a href=\"http:\/\/en.wikipedia.org\/wiki\/Banner_blindness\" target=\"_blank\" rel=\"noopener\">c\u00e9cit\u00e9 de la banni\u00e8re<\/a>\"\u00e0 moins que la page ne contienne un grand nombre de liens.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"So_which_is_best_to_use_for_affiliate_marketing\"><\/span>Quelle est donc la meilleure solution pour le marketing d'affiliation ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Comme nous l'avons dit plus haut, cela d\u00e9pend d'un certain nombre de facteurs.<\/p>\n<p>Si votre site web contient beaucoup de banni\u00e8res publicitaires, il sera probablement plus efficace d'utiliser des liens textuels dans la majorit\u00e9 de vos campagnes d'affiliation.<\/p>\n<p>Cela ne veut pas dire qu'il ne faut pas utiliser de banni\u00e8res. Les banni\u00e8res peuvent \u00eatre tr\u00e8s efficaces pour faire conna\u00eetre la marque et attirer l'attention du visiteur.<\/p>\n<p>Nous vous recommandons toutefois de ne pas exag\u00e9rer le nombre de banni\u00e8res graphiques sur votre site. Si vous g\u00e9rez un site web o\u00f9 vous faites la promotion de plusieurs offres, essayez de faire tourner les banni\u00e8res au lieu de les afficher toutes en m\u00eame temps. Vous augmenterez ainsi votre taux de clics.<\/p>\n<p>Cela peut \u00e9galement d\u00e9pendre de votre public. Pour certains publics, les banni\u00e8res peuvent \u00eatre un peu rebutantes, alors qu'une recommandation dans un article peut \u00eatre le conseil qu'ils veulent suivre.<\/p>\n<p>Si votre public ne se m\u00e9fie pas des banni\u00e8res, elles seront probablement plus efficaces.<\/p>\n<p>En outre, les banni\u00e8res \u00e9tant de formidables outils de reconnaissance de la marque, s'ils voient les identifiants de la marque dans leur int\u00e9gralit\u00e9 plut\u00f4t qu'un simple nom, il se peut qu'ils n'aient d'autre choix que de se pr\u00e9cipiter sur une offre.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Test_And_Tune_Your_Strategy\"><\/span>Testez et ajustez votre strat\u00e9gie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le principe du marketing d'affiliation est de tester et d'ajuster.<\/p>\n<p>Si vous pouvez essayer diff\u00e9rents types d'offres, vous pouvez \u00e9galement essayer d'utiliser plus de banni\u00e8res que de liens textuels.<\/p>\n<p>Pour certains, l'\u00e9quilibre peut se situer quelque part au milieu, mais on ne sait jamais \u00e0 moins de tester.<\/p>","protected":false},"excerpt":{"rendered":"<p>Liens textuels ou banni\u00e8res ? Comprenez les avantages de chacun et d\u00e9terminez la meilleure approche pour vos efforts de marketing.<\/p>","protected":false},"author":1,"featured_media":1180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[251],"tags":[8,155,157,156,158],"class_list":["post-1177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-optimizing-results","tag-affiliate-marketing","tag-banner-links","tag-banners-vs-text-links","tag-text-links","tag-what-is-best"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":0,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/media\/1180"}],"wp:attachment":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}