{"id":4298,"date":"2017-03-28T09:06:37","date_gmt":"2017-03-27T23:06:37","guid":{"rendered":"https:\/\/thirstyaff.wpengine.com\/?p=4298"},"modified":"2017-12-21T10:54:52","modified_gmt":"2017-12-21T00:54:52","slug":"affiliate-guide-write-brilliant-best-post-will-rank","status":"publish","type":"post","link":"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/","title":{"rendered":"Guide de l'affili\u00e9 : Comment \u00e9crire un article brillant qui se classera dans le classement"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenu<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57f7a6df7f7\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #38ad9c;color:#38ad9c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #38ad9c;color:#38ad9c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57f7a6df7f7\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#The_Buzz_with_Best_of_Posts\" >Le buzz avec les meilleurs articles<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#How_to_Write_a_Brilliant_Best_of_Post_that_will_Rank\" >Comment r\u00e9diger un article brillant qui se classera parmi les meilleurs ?<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#Select_your_top_posts_with_Google_Analytics\" >S\u00e9lectionnez les articles les plus consult\u00e9s gr\u00e2ce \u00e0 Google Analytics.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#Choose_the_right_keywords\" >Choisissez les bons mots-cl\u00e9s.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#Strive_for_content_excellence\" >Viser l'excellence du contenu.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#Make_your_headline_balanced\" >Veillez \u00e0 ce que votre titre soit \u00e9quilibr\u00e9.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-guide-write-brilliant-best-post-will-rank\/#Write_relevant_sentences_for_your_embedded_links\" >R\u00e9digez des phrases pertinentes pour vos liens int\u00e9gr\u00e9s.<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4308\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/best-of-post-image-300x169.jpg\" alt=\"poste\" width=\"750\" height=\"422\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/best-of-post-image-300x169.jpg 300w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/best-of-post-image-1024x576.jpg 1024w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/best-of-post-image-768x432.jpg 768w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/best-of-post-image-1536x864.jpg 1536w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/best-of-post-image.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Les entreprises et les blogueurs publient \u00e0 la fin de l'ann\u00e9e un article intitul\u00e9 \"Best of\", qui reprend tous leurs articles les plus populaires. C'est une fa\u00e7on de revenir sur ces moments forts et de voir ce qui a vraiment touch\u00e9 les lecteurs. D'un point de vue marketing, c'est aussi l'occasion de relancer le potentiel de vente d'articles qui ont peu \u00e0 peu perdu de leur vitalit\u00e9.<\/p>\n<p>Les articles \"Best of\" sont tr\u00e8s utiles. Ils peuvent rediriger votre trafic actuel vers des joyaux oubli\u00e9s, et ils cr\u00e9ent une grande valeur de r\u00e9f\u00e9rencement pour votre site.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"The_Buzz_with_Best_of_Posts\"><\/span><strong>Le buzz avec les meilleurs articles<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il y a de nombreuses raisons pour lesquelles ces types de messages fonctionnent. L'une d'entre elles est qu'ils sont r\u00e9dig\u00e9s sous forme de \"liste\", ce qui est l'un des types de contenu les plus efficaces qui soient. Ils sont faciles \u00e0 \"dig\u00e9rer\", contiennent un grand nombre d'informations utiles et vous conf\u00e8rent une certaine autorit\u00e9 en tant que personnalit\u00e9 en ligne.<\/p>\n<p>Jackie Kaufenberg de <a href=\"https:\/\/vimm.com\/blogging-tips\/\">Image vivante<\/a> partage avec nous de pr\u00e9cieuses informations sur les raisons pour lesquelles les blogueurs devraient s'efforcer de cr\u00e9er des articles \"best of\" :<\/p>\n<blockquote>\n<ol>\n<li>L'examen attentif de vos donn\u00e9es d'analyse Google vous donnera une id\u00e9e pr\u00e9cise des articles \u00e0 r\u00e9diger ou \u00e0 d\u00e9velopper pour l'ann\u00e9e suivante.<\/li>\n<li>C'est un excellent moyen de rappeler \u00e0 vos lecteurs et \u00e0 votre personnel tous les excellents articles qui ont \u00e9t\u00e9 publi\u00e9s.<\/li>\n<li>Dans la tradition de la nouvelle ann\u00e9e, cela peut vous aider \u00e0 regarder en arri\u00e8re, analyser et <strong>fixer des objectifs de marketing<\/strong> pour l'ann\u00e9e suivante.<\/li>\n<li>Il vous aide \u00e0 remplir une p\u00e9riode de l'ann\u00e9e difficile \u00e0 \u00e9crire avec un contenu de qualit\u00e9.<\/li>\n<li>Les listes \"Best of\" sont g\u00e9n\u00e9ralement tr\u00e8s rapides et faciles \u00e0 r\u00e9diger. Il suffit de cr\u00e9er la liste et d'ajouter des liens (<strong>Un peu de poussi\u00e8re de f\u00e9e pour les blogs est toujours utile.<\/strong>)!<\/li>\n<li>Lorsqu'elle est bien faite, une liste \"Best of\" peut pr\u00e9senter de nombreux avantages en termes de r\u00e9f\u00e9rencement (d\u00e9veloppez vos sujets avec une description courte et riche en mots-cl\u00e9s de chaque blog).<\/li>\n<li>Il peut vous aider \u00e0 vous rappeler l'\u00e9norme valeur \u00e0 long terme de la <strong>contenu \u00e9volutif<\/strong> dans votre marketing.<\/li>\n<li>Si vous n'avez pas \u00e9crit autant ou aussi souvent que vous l'auriez souhait\u00e9, il peut s'agir de la premi\u00e8re \u00e9tape d'un processus d'apprentissage. <strong>\u00e9tablir un calendrier de blogage coh\u00e9rent<\/strong>.<\/li>\n<\/ol>\n<\/blockquote>\n<p>Si les informations ci-dessus ne sont pas la preuve irr\u00e9futable que les articles \"best of\" valent la peine d'\u00eatre \u00e9crits, je ne sais pas ce que c'est. En fait, il se peut que vous ayez envie de commencer \u00e0 cr\u00e9er les v\u00f4tres d\u00e8s maintenant !<\/p>\n<p>Mais avant de le faire, vous devez savoir ce qu'est la <strong>meilleures pratiques<\/strong> pour qu'il soit bien class\u00e9. Cela signifie que le contenu de votre article doit \u00eatre aussi \"Google-friendly\" que possible. Oui, vous devrez peut-\u00eatre transpirer un peu, mais soyez assur\u00e9 que tous vos efforts seront r\u00e9compens\u00e9s - sous la forme d'une augmentation du trafic, d'une hausse des ventes et d'un flux de nouveaux clients potentiels.<\/p>\n<p>Alors, qu'attendez-vous ? Plongez dans notre guide de r\u00e9daction ci-dessous et laissez le contenu faire le travail \u00e0 votre place.<\/p>\n<h1><span class=\"ez-toc-section\" id=\"How_to_Write_a_Brilliant_Best_of_Post_that_will_Rank\"><\/span><strong>Comment r\u00e9diger un article brillant qui se classera parmi les meilleurs ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><img decoding=\"async\" class=\"wp-image-4310 alignright\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2017\/02\/cartoon-checklist-md.png\" alt=\"\" width=\"159\" height=\"194\" \/>Chaque fois que vous lisez le mot \"classement\", en particulier dans le domaine du marketing d'affiliation, vous devez vous rappeler qu'il a toujours quelque chose \u00e0 voir avec l'optimisation des moteurs de recherche (SEO), ou <strong>optimisation des moteurs de recherche<\/strong>. Il s'ensuit que a <a href=\"https:\/\/thirstyaffiliates.com\/fr\/general\/6-seo-basics-need-master-affiliate-marketing\/\">connaissances de base en mati\u00e8re de r\u00e9f\u00e9rencement<\/a> et une recherche par mots-cl\u00e9s est n\u00e9cessaire.<\/p>\n<p>Et m\u00eame si les net-citoyens se disputent souvent sur les normes actuelles de r\u00e9f\u00e9rencement (parce qu'elles changent TOUT le temps), il y a toujours des r\u00e8gles fondamentales que vous pouvez suivre pour garantir que les moteurs de recherche puissent rep\u00e9rer votre article \"best of\".<\/p>\n<ol>\n<li>\n<h4><span class=\"ez-toc-section\" id=\"Select_your_top_posts_with_Google_Analytics\"><\/span>S\u00e9lectionnez vos meilleurs articles avec <strong>Google Analytics<\/strong>.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 30px;\">Un blogueur intelligent utilise toujours <a href=\"https:\/\/analytics.google.com\/\">Google Analytics<\/a>ou GA, pour suivre leur blog. Ce n'est peut-\u00eatre pas l'outil de pr\u00e9dilection des blogueurs occasionnels (en raison de sa complexit\u00e9), mais croyez-nous quand nous disons que la courbe d'apprentissage en vaut la peine.<\/p>\n<p style=\"padding-left: 30px;\">GA peut vous donner un aper\u00e7u de ce qui se passe sur votre blog, comme le nombre total de visiteurs, les pages vues et le temps pass\u00e9 sur un article, dans un format facile \u00e0 comprendre. <a href=\"http:\/\/www.wildapricot.com\/blogs\/newsblog\/2007\/06\/25\/how-to-use-google-analytics-to-track-your-top-blog-posts\">Ce billet sur l'utilisation de GA<\/a> de WildApricot vous explique comment trouver les donn\u00e9es souhait\u00e9es et les exporter sous forme de fichier de feuille de calcul (.CSV).<\/p>\n<ol start=\"2\">\n<li>\n<h4><span class=\"ez-toc-section\" id=\"Choose_the_right_keywords\"><\/span>Choisissez les bons mots-cl\u00e9s.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 30px;\">Une fois que vous avez une bonne liste d'articles \u00e0 pr\u00e9senter, votre prochaine t\u00e2che consiste \u00e0 rechercher des mots-cl\u00e9s. <a href=\"https:\/\/adwords.google.com\/KeywordPlanner\">Planificateur de mots-cl\u00e9s de Google<\/a> est tr\u00e8s utile \u00e0 cet \u00e9gard. Vous pouvez l'utiliser pour identifier les zones <strong>faible concurrence<\/strong> et <strong>volume de recherche \u00e9lev\u00e9<\/strong> avec des possibilit\u00e9s de classement. Une fois que vous avez \u00e9tabli une liste de mots-cl\u00e9s \u00e0 cibler, vous pouvez les int\u00e9grer dans votre article \"best of\".<\/p>\n<ol start=\"3\">\n<li>\n<h4><span class=\"ez-toc-section\" id=\"Strive_for_content_excellence\"><\/span>Viser l'excellence du contenu.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 30px;\">Avant d'utiliser une quelconque strat\u00e9gie pour am\u00e9liorer le classement de votre article, assurez-vous d'abord de peaufiner vos comp\u00e9tences en mati\u00e8re d'\u00e9criture. Une \u00e9criture minable ne suffira pas. Si votre article de blog est truff\u00e9 d'absurdit\u00e9s que les lecteurs n'appr\u00e9cieront pas, Google ne vous aimera pas non plus. Vos lecteurs doivent toujours \u00eatre votre priorit\u00e9 num\u00e9ro un - sinon vous les d\u00e9couragerez de votre blog et tous vos efforts seront vains.<\/p>\n<ol start=\"4\">\n<li>\n<h4><span class=\"ez-toc-section\" id=\"Make_your_headline_balanced\"><\/span>Veillez \u00e0 ce que votre titre soit \u00e9quilibr\u00e9.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 30px;\">Vous connaissez d\u00e9j\u00e0 les deux r\u00e8gles les plus importantes : utilisez des mots-cl\u00e9s, mais donnez la priorit\u00e9 \u00e0 votre public. Gardez ces deux r\u00e8gles \u00e0 l'esprit lorsque vous cr\u00e9ez un titre. <a href=\"https:\/\/blog.hubspot.com\/marketing\/seo-friendly-blog-post-checklist-ht\">Hubspot<\/a> recommande d'inclure le(s) mot(s) cl\u00e9(s) principal(aux) dans les 65 premiers caract\u00e8res.<\/p>\n<ol start=\"5\">\n<li>\n<h4><span class=\"ez-toc-section\" id=\"Write_relevant_sentences_for_your_embedded_links\"><\/span>R\u00e9digez des phrases pertinentes pour vos liens int\u00e9gr\u00e9s.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<\/li>\n<\/ol>\n<p style=\"padding-left: 30px;\">Les expressions telles que \"cliquez ici\" ou \"lisez la suite\" sont les textes d'ancrage pr\u00e9f\u00e9r\u00e9s des blogueurs, mais la v\u00e9rit\u00e9 est qu'elles ne vous permettent pas d'optimiser le r\u00e9f\u00e9rencement de votre article \"best of\". Pour obtenir les meilleurs r\u00e9sultats, veillez toujours \u00e0 ce que votre texte d'ancrage soit descriptif, int\u00e9ressant et pertinent. Faites-le lorsque vous souhaitez cr\u00e9er un lien vers vos autres articles de blog, pages ou services.<\/p>\n<p style=\"padding-left: 30px;\">Exemple : \"Utilisation d'un plugin qui <a href=\"https:\/\/wordpress.org\/plugins\/thirstyaffiliates\/\">place automatiquement des liens d'affiliation<\/a> est un excellent moyen d'\u00e9conomiser du temps et de l'\u00e9nergie lors de la r\u00e9daction d'\u00e9valuations de produits\". (Vous voyez ce que j'ai fait ?)<\/p>\n<p><strong>Voil\u00e0, c'est fait.<\/strong><\/p>\n<p>Si vous souhaitez r\u00e9diger un excellent article \"best of\", \u00e9tablissez une liste de contr\u00f4le sur la base de notre guide ci-dessus et vous devriez \u00eatre en mesure de le faire. Ne vous inqui\u00e9tez pas s'il faut du temps pour que votre article soit class\u00e9. N'oubliez pas qu'il s'agit de r\u00e9f\u00e9rencement et que vous devez laisser les choses se d\u00e9rouler \u00e0 un rythme lent et r\u00e9gulier pour obtenir des r\u00e9sultats durables.<\/p>\n<p><em>Sur quel article \"best of\" travaillez-vous en ce moment ? Partagez vos id\u00e9es ci-dessous et nous nous ferons un plaisir de vous donner nos propres conseils !<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>A \u201cBest of\u201d post is something that companies and bloggers publish at the end of the year that features all their most popular articles. It\u2019s a way of looking back at those golden moments and seeing what really resonated with readers. From a marketing perspective, it\u2019s also a chance to revive the sales potential of&hellip;<\/p>","protected":false},"author":1710,"featured_media":4308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-increasing-sales"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/4298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/users\/1710"}],"replies":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/comments?post=4298"}],"version-history":[{"count":0,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/4298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/media\/4308"}],"wp:attachment":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/media?parent=4298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/categories?post=4298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/tags?post=4298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}