{"id":8835,"date":"2018-06-19T08:00:41","date_gmt":"2018-06-18T22:00:41","guid":{"rendered":"https:\/\/thirstyaff.wpengine.com\/?p=8835"},"modified":"2020-07-30T07:24:32","modified_gmt":"2020-07-29T21:24:32","slug":"affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond","status":"publish","type":"post","link":"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond","title":{"rendered":"Interview d'un affili\u00e9 : Charles Ngo (Comment devenir un James Bond asiatique)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenu<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04b8f8d3c4a\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #38ad9c;color:#38ad9c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #38ad9c;color:#38ad9c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04b8f8d3c4a\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#1_Hey_Charles_thanks_so_much_for_coming_on_for_an_interview_Im_a_big_fan_and_have_been_following_you_for_quite_a_few_years\" >1. Charles, merci beaucoup d'\u00eatre venu nous interviewer. Je suis un grand fan et je vous suis depuis quelques ann\u00e9es.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#I_think_one_of_the_big_differences_between_you_and_me_is_that_you_are_a_CPA_Cost_Per_Action_style_affiliate_whereas_I_concentrate_more_on_CPS_Cost_Per_Sale_style_affiliate_marketing\" >Je pense que l'une des grandes diff\u00e9rences entre vous et moi est que vous \u00eates un affili\u00e9 de type CPA (co\u00fbt par action), alors que je me concentre davantage sur le marketing d'affiliation de type CPS (co\u00fbt par vente).<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#For_the_folks_who_maybe_dont_know_much_about_CPA_can_you_explain_the_difference_and_what_makes_you_favor_the_CPA_versus_the_CPS_model\" >Pour les personnes qui ne connaissent peut-\u00eatre pas bien l'ACP, pouvez-vous expliquer la diff\u00e9rence et ce qui vous fait pr\u00e9f\u00e9rer le mod\u00e8le de l'ACP \u00e0 celui de la SCP ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#2_For_a_newbie_affiliate_%E2%80%94_someone_coming_into_affiliate_marketing_raw_after_just_learning_what_it_is_%E2%80%94_what_would_be_the_number_1_thing_you_think_they_should_focus_on_first_if_they_wanted_to_be_a_CPA_affiliate\" >2. Pour un affili\u00e9 d\u00e9butant - quelqu'un qui se lance dans le marketing d'affiliation apr\u00e8s avoir appris ce que c'est - quelle serait, selon vous, la premi\u00e8re chose sur laquelle il devrait se concentrer s'il voulait devenir un affili\u00e9 CPA ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#3_One_of_the_things_I_always_tell_people_wanting_to_achieve_success_in_affiliate_marketing_and_business_in_general_is_to_take_big_action\" >3. L'une des choses que je dis toujours aux personnes qui veulent r\u00e9ussir dans le marketing d'affiliation et dans les affaires en g\u00e9n\u00e9ral, c'est de prendre des mesures importantes.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#I_know_youre_a_big_proponent_of_this_too_How_important_is_it_to_have_a_game_plan_and_how_do_you_go_about_getting_organized_to_that_level\" >Je sais que vous en \u00eates un fervent partisan. Quelle est l'importance d'avoir un plan de match et comment vous y prenez-vous pour vous organiser \u00e0 ce niveau ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#4_If_you_had_to_start_again_tomorrow_what_would_be_the_first_thing_youd_do_to_rebuild_your_affiliate_marketing_empire\" >4. Si vous deviez recommencer demain, quelle serait la premi\u00e8re chose que vous feriez pour reconstruire votre empire de marketing d'affiliation ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#5_You_have_traveled_a_lot_and_youve_visited_and_lived_in_some_interesting_places_all_around_the_world_from_America_to_Asia_Now_youve_settled_in_New_York_and_have_been_there_for_a_while_What_made_you_choose_New_York\" >5. Vous avez beaucoup voyag\u00e9 et vous avez visit\u00e9 et v\u00e9cu dans des endroits int\u00e9ressants dans le monde entier, de l'Am\u00e9rique \u00e0 l'Asie. Aujourd'hui, vous vous \u00eates install\u00e9 \u00e0 New York et vous y vivez depuis un certain temps. Qu'est-ce qui vous a fait choisir New York ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#6_Whats_on_the_cards_for_the_rest_of_2018_for_Charles_Ngo\" >6. Qu'est-ce qui attend Charles Ngo pour le reste de l'ann\u00e9e 2018 ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\/#7_Where_can_people_find_you_and_follow_what_youre_doing\" >7. O\u00f9 les gens peuvent-ils vous trouver et suivre ce que vous faites ?<\/a><\/li><\/ul><\/nav><\/div>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-8836 size-full\" src=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2018\/06\/Charles-Ngo-Affiliate-Interview-1.jpg\" alt=\"Charles Ngo Affiliate Marketing co\u00fbt par action\" width=\"814\" height=\"426\" srcset=\"https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2018\/06\/Charles-Ngo-Affiliate-Interview-1.jpg 814w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2018\/06\/Charles-Ngo-Affiliate-Interview-1-300x157.jpg 300w, https:\/\/thirstyaffiliates.com\/wp-content\/uploads\/2018\/06\/Charles-Ngo-Affiliate-Interview-1-768x402.jpg 768w\" sizes=\"(max-width: 814px) 100vw, 814px\" \/><\/p>\n<p>Dans le blog d'aujourd'hui, nous avons un personnage tr\u00e8s int\u00e9ressant et tr\u00e8s connu dans le domaine du marketing d'affiliation.<\/p>\n<p>Vous l'avez peut-\u00eatre vu lors de conf\u00e9rences ou en ligne. Il est souvent (lui-m\u00eame ?) d\u00e9crit comme un James Bond asiatique.<\/p>\n<p>Quoi qu'il en soit, je pense que nous sommes tous d'accord pour dire que c'est un homme tr\u00e8s habile, et qu'il conna\u00eet certainement son m\u00e9tier en mati\u00e8re de marketing d'affiliation.<\/p>\n<p>Je suis Charles Ngo depuis quelques ann\u00e9es maintenant, et je suis toujours stup\u00e9fait par toutes les choses de grande valeur qu'il donne \u00e0 ses lecteurs sur son blog. S\u00e9rieusement, si vous ne l'avez pas encore fait, t\u00e9l\u00e9chargez gratuitement son guide ultime du marketing d'affiliation. <a href=\"https:\/\/charlesngo.com\/\" rel=\"noopener\">de son site web.<\/a> Il vous ouvrira les yeux.<\/p>\n<p>Quant \u00e0 la raison pour laquelle j'ai voulu qu'il participe au blog, c'est parce que je parle beaucoup de blogs, de contenu et de construction de sites, alors qu'il se concentre davantage sur l'acquisition payante et les campagnes de type co\u00fbt par action. Des coups diff\u00e9rents pour des gens diff\u00e9rents. Je pense vraiment que cette interview vous apportera beaucoup pour cette raison.<\/p>\n<p>Passons \u00e0 l'interview, parce que c'\u00e9tait une bonne interview !<\/p>\n<h3><span class=\"ez-toc-section\" id=\"1_Hey_Charles_thanks_so_much_for_coming_on_for_an_interview_Im_a_big_fan_and_have_been_following_you_for_quite_a_few_years\"><\/span>1. Charles, merci beaucoup d'\u00eatre venu nous interviewer. Je suis un grand fan et je vous suis depuis quelques ann\u00e9es.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h3><span class=\"ez-toc-section\" id=\"I_think_one_of_the_big_differences_between_you_and_me_is_that_you_are_a_CPA_Cost_Per_Action_style_affiliate_whereas_I_concentrate_more_on_CPS_Cost_Per_Sale_style_affiliate_marketing\"><\/span>Je pense que l'une des grandes diff\u00e9rences entre vous et moi est que vous \u00eates un affili\u00e9 de type CPA (co\u00fbt par action), alors que je me concentre davantage sur le marketing d'affiliation de type CPS (co\u00fbt par vente).<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h3><span class=\"ez-toc-section\" id=\"For_the_folks_who_maybe_dont_know_much_about_CPA_can_you_explain_the_difference_and_what_makes_you_favor_the_CPA_versus_the_CPS_model\"><\/span>Pour les personnes qui ne connaissent peut-\u00eatre pas bien l'ACP, pouvez-vous expliquer la diff\u00e9rence et ce qui vous fait pr\u00e9f\u00e9rer le mod\u00e8le de l'ACP \u00e0 celui de la SCP ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Bien s\u00fbr, merci de m'accueillir.<\/p>\n<p>Co\u00fbt par vente : Vous faites la promotion d'un produit. Le client doit ACHETER le produit, puis l'affili\u00e9 re\u00e7oit une commission.<\/p>\n<p>Co\u00fbt par action : Vous faites la promotion d'une offre. Le client doit effectuer une ACTION, puis l'affili\u00e9 re\u00e7oit une commission.<\/p>\n<p>Le co\u00fbt par vente est g\u00e9n\u00e9ralement plus difficile \u00e0 convertir car il faut convaincre la personne de sortir sa carte de cr\u00e9dit et d'acheter quelque chose.<\/p>\n<p>Le co\u00fbt par action est plus facile \u00e0 convertir. L'\"action\" peut consister \u00e0 remplir un formulaire avec le nom, l'adresse \u00e9lectronique et le num\u00e9ro de t\u00e9l\u00e9phone de la personne, puis \u00e0 \u00eatre pay\u00e9. L'annonceur gagne de l'argent parce qu'il suit les informations de la personne et essaie de la vendre par la suite.<\/p>\n<p>Pensez au fait qu'il est beaucoup plus facile pour quelqu'un d'entreprendre une action que pour quelqu'un qui sort sa carte de cr\u00e9dit et ach\u00e8te quelque chose.<\/p>\n<p>Ce qui est int\u00e9ressant, c'est qu'il n'y a pas tant de diff\u00e9rence si vous \u00eates un sp\u00e9cialiste du marketing d'affiliation. Certaines offres proposent les deux fa\u00e7ons de mon\u00e9tiser.<\/p>\n<p>Vous pouvez promouvoir une offre de rencontre \u00e0 la mani\u00e8re du CPA, o\u00f9 les internautes remplissent leurs informations. Vous pouvez \u00e9galement promouvoir cette m\u00eame offre de rencontres par le biais du CPS, o\u00f9 vous \u00eates mieux pay\u00e9 si la personne s'inscrit et ach\u00e8te.<\/p>\n<p>Je sugg\u00e8re de commencer par le style CPA parce qu'il est plus facile \u00e0 convertir et qu'il permet d'obtenir plus de donn\u00e9es.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2_For_a_newbie_affiliate_%E2%80%94_someone_coming_into_affiliate_marketing_raw_after_just_learning_what_it_is_%E2%80%94_what_would_be_the_number_1_thing_you_think_they_should_focus_on_first_if_they_wanted_to_be_a_CPA_affiliate\"><\/span>2. Pour un affili\u00e9 d\u00e9butant - quelqu'un qui se lance dans le marketing d'affiliation apr\u00e8s avoir appris ce que c'est - quelle serait, selon vous, la premi\u00e8re chose sur laquelle il devrait se concentrer s'il voulait devenir un affili\u00e9 CPA ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La chose la plus importante est de d\u00e9cider de la voie \u00e0 suivre. Je vois des gens qui perdent des mois \u00e0 faire des allers-retours.<\/p>\n<p>Un mois, ils sont sp\u00e9cialis\u00e9s dans le commerce \u00e9lectronique. Un autre mois, c'est un gars de la t\u00e9l\u00e9phonie mobile. Un autre mois, c'est un gars de Facebook.<\/p>\n<p>Ils sont atteints du syndrome de l'objet brillant.<\/p>\n<p>Choisissez une voie et consacrez-y au moins trois mois.<\/p>\n<p>Par exemple, disons que vous d\u00e9cidez de devenir un affili\u00e9 mobile. Passez les trois prochains mois \u00e0 \u00e9tudier le plus possible le mobile et \u00e0 apprendre le plus grand nombre possible de campagnes mobiles.<\/p>\n<p>Vous ne pouvez pas tout \u00e9tudier dans le domaine du marketing d'affiliation, mais vous pouvez en ma\u00eetriser une partie.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"3_One_of_the_things_I_always_tell_people_wanting_to_achieve_success_in_affiliate_marketing_and_business_in_general_is_to_take_big_action\"><\/span>3. L'une des choses que je dis toujours aux personnes qui veulent r\u00e9ussir dans le marketing d'affiliation et dans les affaires en g\u00e9n\u00e9ral, c'est de prendre des mesures importantes.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h3><span class=\"ez-toc-section\" id=\"I_know_youre_a_big_proponent_of_this_too_How_important_is_it_to_have_a_game_plan_and_how_do_you_go_about_getting_organized_to_that_level\"><\/span>Je sais que vous en \u00eates un fervent partisan. Quelle est l'importance d'avoir un plan de match et comment vous y prenez-vous pour vous organiser \u00e0 ce niveau ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Soit les gens planifient trop et n'agissent pas, soit ils ne planifient pas et agissent trop.<\/p>\n<p>Le plus difficile pour les gens est de trouver l'\u00e9quilibre entre la planification et l'action.<\/p>\n<p>J'ai toujours un plan de match pour tout ce que je fais. L'essentiel est qu'une fois ce plan \u00e9tabli, je passe en mode ex\u00e9cution. Ne commettez pas l'erreur d'\u00e9tablir un plan puis de le modifier sans cesse.<\/p>\n<p>Pour ce qui est de l'organisation, j'aime utiliser un syst\u00e8me appel\u00e9 AgileResults. Il s'agit d'un syst\u00e8me simple qui utilise la r\u00e8gle des trois.<\/p>\n<p>Chaque ann\u00e9e, j'ai trois objectifs \u00e0 atteindre. Cela se traduit par trois r\u00e9sultats pour le mois, pour la semaine et pour le jour. C'est un syst\u00e8me en cascade.<\/p>\n<p>En limitant mes objectifs \u00e0 trois, je reste organis\u00e9e et concentr\u00e9e.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"4_If_you_had_to_start_again_tomorrow_what_would_be_the_first_thing_youd_do_to_rebuild_your_affiliate_marketing_empire\"><\/span>4. Si vous deviez recommencer demain, quelle serait la premi\u00e8re chose que vous feriez pour reconstruire votre empire de marketing d'affiliation ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Je pars du principe que je commence avec z\u00e9ro dollar et aucune connaissance en mati\u00e8re de marketing d'affiliation.<\/p>\n<p>La premi\u00e8re chose que je ferais serait d'augmenter mes liquidit\u00e9s. Cela pourrait signifier trouver un emploi. J'ai vu trop de gens vouloir savoir comment gagner de l'argent en ligne avec un budget de $200. C'est difficile. Vous pouvez \u00e0 peine payer les outils avec ce budget.<\/p>\n<p>Plus vous pouvez investir dans votre entreprise, plus vous avez de chances de r\u00e9ussir.<\/p>\n<p>Deuxi\u00e8mement, je ferais de mon mieux pour trouver un mentor.<\/p>\n<p>Rappelez-vous ceci : personne ne vous doit rien. Quelle valeur pouvez-vous apporter \u00e0 quelqu'un pour qu'il vous aide ?<\/p>\n<p>Ensuite, je ferais de la r\u00e9tro-ing\u00e9nierie sur ce qui fonctionne. J'investirais dans un outil d'espionnage et j'examinerais les principales campagnes en cours. Qu'ont-elles en commun ? Quel type d'offre propose-t-on ? Quel type de pages d'atterrissage ?<\/p>\n<p>Imiter, puis innover.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"5_You_have_traveled_a_lot_and_youve_visited_and_lived_in_some_interesting_places_all_around_the_world_from_America_to_Asia_Now_youve_settled_in_New_York_and_have_been_there_for_a_while_What_made_you_choose_New_York\"><\/span>5. Vous avez beaucoup voyag\u00e9 et vous avez visit\u00e9 et v\u00e9cu dans des endroits int\u00e9ressants dans le monde entier, de l'Am\u00e9rique \u00e0 l'Asie. Aujourd'hui, vous vous \u00eates install\u00e9 \u00e0 New York et vous y vivez depuis un certain temps. Qu'est-ce qui vous a fait choisir New York ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>L'endroit o\u00f9 vous choisissez de vivre a un effet consid\u00e9rable sur votre bonheur et votre qualit\u00e9 de vie !<\/p>\n<p>Heureusement, j'ai une carri\u00e8re qui me permet de vivre o\u00f9 je veux, et j'en ai profit\u00e9. Je d\u00e9m\u00e9nage chaque ann\u00e9e parce que j'ai toujours \u00e9t\u00e9 curieuse.<\/p>\n<p>En ce qui concerne NYC, j'ai d\u00e9m\u00e9nag\u00e9 ici pour plusieurs raisons. La principale est que j'ai 33 ans et que je ne suis pas mari\u00e9e. J'ai senti que la fen\u00eatre se refermait pour que je puisse vivre \u00e0 New York avant de m'installer.<\/p>\n<p>J'ai toujours voulu vivre \u00e0 New York depuis mon enfance. C'est cher de vivre ici, mais je peux toujours gagner plus d'argent.<\/p>\n<p>Les exp\u00e9riences et la croissance que j'ai pu vivre ici n'ont pas de prix.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"6_Whats_on_the_cards_for_the_rest_of_2018_for_Charles_Ngo\"><\/span>6. Qu'est-ce qui attend Charles Ngo pour le reste de l'ann\u00e9e 2018 ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nous pr\u00e9voyons de lancer nos premiers cours en ligne dans le courant de l'ann\u00e9e.<\/p>\n<p>Ces derni\u00e8res ann\u00e9es, j'ai enseign\u00e9 \u00e0 des personnes dans le cadre d'ateliers en personne. Nous avons d\u00e9cid\u00e9 de passer \u00e0 des cours en ligne, principalement parce que le mod\u00e8le de l'atelier est \u00e9puisant.<\/p>\n<p>En dehors de cela, je me concentre sur l'apprentissage et la croissance !<\/p>\n<h3><span class=\"ez-toc-section\" id=\"7_Where_can_people_find_you_and_follow_what_youre_doing\"><\/span>7. O\u00f9 les gens peuvent-ils vous trouver et suivre ce que vous faites ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Je ne suis plus active sur les m\u00e9dias sociaux. Le meilleur endroit pour me trouver est mon blog, <a href=\"https:\/\/charlesngo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.CharlesNgo.com.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans le blog d'aujourd'hui, nous avons un personnage tr\u00e8s int\u00e9ressant et tr\u00e8s connu dans le domaine du marketing d'affiliation. Vous l'avez peut-\u00eatre vu lors de conf\u00e9rences ou en ligne. Il est souvent (auto ?) d\u00e9crit comme un James Bond asiatique. Quoi qu'il en soit, je pense que nous sommes tous d'accord pour dire que c'est un homme tr\u00e8s habile et qu'il s'y conna\u00eet en mati\u00e8re de marketing d'affiliation.<\/p>\n<p><a class=\"read-more\" href=\"https:\/\/thirstyaffiliates.com\/fr\/blog\/affiliate-interview-charles-ngo-how-to-be-an-asian-james-bond\">Lire la suite<\/a><\/p>","protected":false},"author":1,"featured_media":8836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[249],"tags":[],"class_list":["post-8835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies-and-interviews"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/8835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/comments?post=8835"}],"version-history":[{"count":0,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/8835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/media\/8836"}],"wp:attachment":[{"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/media?parent=8835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/categories?post=8835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thirstyaffiliates.com\/fr\/wp-json\/wp\/v2\/tags?post=8835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}